{"id":196112,"date":"2026-07-23T15:21:20","date_gmt":"2026-07-23T13:21:20","guid":{"rendered":"https:\/\/factorialhr.com\/blog\/factorial-play\/videos\/o-salario-nao-basta-para-reter-talento\/"},"modified":"2026-07-23T15:21:20","modified_gmt":"2026-07-23T13:21:20","slug":"o-salario-nao-basta-para-reter-talento","status":"publish","type":"factorial_video","link":"https:\/\/factorialhr.pt\/blog\/factorial-play\/videos\/o-salario-nao-basta-para-reter-talento\/","title":{"rendered":"O sal\u00e1rio n\u00e3o basta para reter talento"},"featured_media":0,"template":"","meta":{"_acf_changed":false,"_video_type":"highlight","_related_series":192403,"_related_episode":196089,"_related_season":0,"_video_source":"vimeo","_youtube_video_id":"","_vimeo_video_id":"1211769654","_speaker_id":196088,"_video_description":"No v\u00eddeo, Isabel Aranda e Carla Ripa discutem por que o dinheiro, por si s\u00f3, j\u00e1 n\u00e3o \u00e9 suficiente para reter talentos nas empresas. Eles destacam que, sem v\u00ednculo, n\u00e3o h\u00e1 lealdade, enfatizando a import\u00e2ncia da cultura empresarial e do alinhamento entre os objetivos pessoais e os valores da empresa. A comunica\u00e7\u00e3o clara e a gest\u00e3o do time s\u00e3o essenciais para fortalecer esses v\u00ednculos e fomentar um plano de carreira que valorize todos os colaboradores, principalmente aqueles com mais experi\u00eancia. A mudan\u00e7a nas expectativas das novas gera\u00e7\u00f5es tamb\u00e9m \u00e9 abordada, ressaltando que a identidade profissional n\u00e3o deve ser a \u00fanica fonte de valor na vida. Para mais dicas e insights sobre lideran\u00e7a e gest\u00e3o, n\u00e3o perca o epis\u00f3dio completo.","_video_transcription":"00:08 - Pergunta 3: Por que \u00e9 que o dinheiro, por si s\u00f3, j\u00e1 n\u00e3o ret\u00e9m ningu\u00e9m?\n00:12 - A) O sal\u00e1rio n\u00e3o chega.B) As regras mudaram.C) Sem v\u00ednculo, n\u00e3o h\u00e1 lealdade.\n00:18 - D) O joker.Escolho a op\u00e7\u00e3o \u00aboutro\u00bb porque todas as op\u00e7\u00f5es apresentadas s\u00e3o reais e explicam um pouco do que se est\u00e1 a passar. Ent\u00e3o, o Joker.\n00:27 - Bem, neste caso, estou mais inclinado para as op\u00e7\u00f5es A e C, sobretudo.\n00:31 - Por isso, acho que vou ficar com a op\u00e7\u00e3o C; sem v\u00ednculo, n\u00e3o h\u00e1 lealdade.\n00:37 - Para mim, as tr\u00eas fazem sentido.Estava indeciso entre a A e a C, mas acabei por optar pela C porque tenho a sensa\u00e7\u00e3o de que o A j\u00e1 abrange muitas coisas,j\u00e1 que o sal\u00e1rio n\u00e3o chega.\n00:46 - E hoje em dia, como h\u00e1 muito mais coisas que est\u00e3o a ganhar cada vez mais relev\u00e2ncia, como, por exemplo, aquilo de que j\u00e1 fal\u00e1mos sobre o crescimento, o progresso,dos benef\u00edcios, da flexibilidade, assim como de muitas outras coisas que entram em jogo no pr\u00f3prio \u00e2mbito da ideia de que o sal\u00e1rio n\u00e3o \u00e9 suficiente.\n00:59 - E ent\u00e3o pensei que o C significava que, sem v\u00ednculo, n\u00e3o h\u00e1 lealdade,fez-me pensar muito na cultura empresarial.\n01:07 - E parece-me que \u00e9 um tema muito relevante e, na verdade,Quando comecei na Factorial, comecei a trabalhar na \u00e1rea cultural.\n01:14 - E \u00e9 uma das coisas de que mais gosto, na verdade.\n01:19 - Tamb\u00e9m adoro o desenvolvimento, mas, no fundo, \u00e9 uma das coisas o que me deixa muito entusiasmado, porque acho que \u00e9 muito, muito importante que o teu objetivo na vida esteja intimamente ligado ao pr\u00f3prio projeto da empresa,parece que h\u00e1 uma certa coer\u00eancia entre o projeto que tenho a empresa e o teu objetivo.\n01:36 - Parece-me muito importante integrar-me e sentir-me parte de algo,al\u00e9m, claro, do facto de sentires que o que fazes Est\u00e1 bem, e tu est\u00e1s a fazer a diferen\u00e7a, fazes parte de um mecanismo.\n01:48 - Acho que h\u00e1 muitos aspetos que s\u00e3o muito relevantes.\n01:52 - Concordo plenamente.A verdade \u00e9 que aqui tudo \u00e9 importante; j\u00e1 viram que eu foi apanhado com o Joker.\n01:59 - Mas, vamos l\u00e1, princ\u00edpios b\u00e1sicos.Como podem ver, gosto de ir a coisas bem simples.\n02:06 - A pir\u00e2mide de Maslow, e ele dizia-nos: o mais importante s\u00e3o as necessidades Para sobreviver, preciso de dinheiro para comer.\n02:13 - E \u00e9 verdade que preciso de um sal\u00e1rio para poder Ou n\u00e3o, mas enfim,Vamos ficar por aqui: preciso de um rendimento.\n02:20 - Preciso de um rendimento para poder comer, como dizia Cervantes,Com fome, n\u00e3o se escrevem sonetos.\n02:27 - Ent\u00e3o, h\u00e1 uma esp\u00e9cie de ordem.Mas, neste momento, \u00e9 muito importante ter uma vis\u00e3o macrosocial.\n02:36 - Desde a COVID, foi como um momento decisivo em que as pessoas percebeu que a vida pode acabar num instante e que ter de aguentar um emprego em aquilo que n\u00e3o te satisfaz, tu tens o que \u00e9 preciso fazer no menor tempo poss\u00edvel.\n02:55 - Sem d\u00favida, provavelmente este n\u00e3o \u00e9 o s\u00edtio certo para ti.\n02:57 - Haver\u00e1 um lugar para ti, com toda a certeza.Ent\u00e3o, as regras mudaram.\n03:02 - Atualmente, a rela\u00e7\u00e3o das pessoas com o trabalho \u00e9 diferente.\n03:06 - H\u00e1 muita gente que diz: \u00ab\u00c9 que a Gera\u00e7\u00e3o Z \u00e9\u00bb \u00abaquela que mudou as regras\u00bb.\n03:09 - N\u00e3o, olha, n\u00e3o.As regras v\u00eam mudando h\u00e1 muitos anos.\n03:12 - \u00c9 que quando a gera\u00e7\u00e3o Y chegou, eu lembro-me bem disso, de ouvir os diretores de recursos humanos: \u00abUau!\u00bb \u00abEssas pessoas, n\u00e3o h\u00e1 maneira de\u00bb. Claro, cada gera\u00e7\u00e3o j\u00e1 trouxe uma evolu\u00e7\u00e3o social, uma mudan\u00e7a, houve uma melhoria,at\u00e9 agora, tem havido uma melhoria social.\n03:29 - E isso significava que tinhas visto os teus pais a trabalhar de uma certa Dessa forma, procuravas sempre viver melhor, trabalhar melhor.\n03:36 - E isso fez com que a liga\u00e7\u00e3o, a ideia de: \u00abque tipo de rela\u00e7\u00e3o devo ter \u00abE eu, com o trabalho?\u00bb tenha mudado.\n03:42 - Hoje em dia, as pessoas trabalham apenas o suficiente para poderem viver bem,mas n\u00e3o vive para trabalhar.\n03:50 - E antigamente as pessoas viviam para trabalhar, porque entendiam que a sua identidade profissional, h\u00e1 alguns que ainda l\u00e1 est\u00e3o,mas \u00e9 a identidade profissional que te d\u00e1 valor.\n04:01 - Para quem isso funciona, funciona mesmo; afinal, nem todos estamos no mesmo n\u00edvel.\n04:06 - Mas reparem que a identidade profissional tem a ver com o que fazes, onde o fazes, em que ponto o fazes e em que posi\u00e7\u00e3o o fazes.\n04:16 - H\u00e1 muitas pessoas para quem essa identidade profissional \u00e9 tudo na vida e que, quando se reformam ou s\u00e3o despedidos, tudo isso lhes escapa.\n04:25 - Ent\u00e3o, est\u00e1s a falar-me do prop\u00f3sito da vida, e o que se passa \u00e9 que o meu prop\u00f3sito na vida era permanecer nessa empresa e ocupar esse cargo.\n04:31 - Muitas pessoas que n\u00e3o se reformam.De facto, e h\u00e1 muita gente que n\u00e3o suporta ter deixado o emprego,que n\u00e3o consegue suportar isso porque: \u00abQual \u00e9 a minha identidade agora?\u00bb \u00abE agora, quem sou eu?\u00bb Ent\u00e3o, repara que h\u00e1 pessoas, h\u00e1 empresas muito interessantes,Estou a trabalhar num projeto muito interessante com pessoas com mais de 50 anos com o passar dos anos, porque, claro, come\u00e7am a perder o v\u00ednculo.\n04:51 - E por que \u00e9 que come\u00e7am a perder o v\u00ednculo?Porque dizem: \u00abPara o que me resta?\u00bb.\n04:55 - Ent\u00e3o, como reativar esse v\u00ednculo? Como promover essa ideia de legado?\n04:59 - Como valorizar a terceira idade?Bem, s\u00e3o medidas que algumas empresas est\u00e3o a tomar neste momento.\n05:05 - Portanto, o v\u00ednculo n\u00e3o se resume apenas ao facto de te manteres numa empresa,\u00e9 quando est\u00e1s na empresa, o que est\u00e1s a oferecer \u00e0 empresa,Que valores acrescentas \u00e0 empresa.\n05:16 - Meninas, muito obrigada por partilharem a vossa experi\u00eancia,foi uma experi\u00eancia muito enriquecedora.\n05:20 - O debate terminou, muito obrigado.Bem, obrigado a ti, obrigado \u00e0 Factorial.\n05:25 - J\u00e1 nos cruz\u00e1mos outras vezes, mas ainda n\u00e3o tivemos oportunidade de fiar De fazer um a.\n05:30 - De apresentarmos as nossas ideias desta forma.Concretizar as nossas ideias.\n05:33 - Ent\u00e3o, quando quiseres, podemos encontrar-nos novamente.\n05:36 - Maravilhoso. J\u00e1 temos tudo organizado.Sem d\u00favida. Vamos l\u00e1.","_has_trailer":false,"_trailer_vimeo_id":"","_trailer_youtube_id":"","_video_duration":"","_video_thumbnail":""},"categories":[940,996],"factorial-categories":[],"class_list":["post-196112","factorial_video","type-factorial_video","status-publish","hentry","category-crescimento-da-equipa","category-insights-de-lideranca-pt-pt"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.5 (Yoast SEO v21.9.1) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>O sal\u00e1rio n\u00e3o basta para reter talento | Factorial<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/factorialhr.pt\/blog\/factorial-play\/videos\/o-salario-nao-basta-para-reter-talento\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O sal\u00e1rio n\u00e3o basta para reter talento\" \/>\n<meta property=\"og:url\" content=\"https:\/\/factorialhr.pt\/blog\/factorial-play\/videos\/o-salario-nao-basta-para-reter-talento\/\" \/>\n<meta property=\"og:site_name\" content=\"Factorial\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/\" \/>\n<meta property=\"og:image\" content=\"https:\/\/factorialhr.pt\/wp-content\/uploads\/2025\/11\/17131146\/factorial-open-graph.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@factorialapp\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/factorialhr.pt\/blog\/factorial-play\/videos\/o-salario-nao-basta-para-reter-talento\/\",\"url\":\"https:\/\/factorialhr.pt\/blog\/factorial-play\/videos\/o-salario-nao-basta-para-reter-talento\/\",\"name\":\"O sal\u00e1rio n\u00e3o basta para reter talento | Factorial\",\"isPartOf\":{\"@id\":\"https:\/\/factorialhr.pt\/blog\/#website\"},\"datePublished\":\"2026-07-23T13:21:20+00:00\",\"dateModified\":\"2026-07-23T13:21:20+00:00\",\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/factorialhr.pt\/blog\/factorial-play\/videos\/o-salario-nao-basta-para-reter-talento\/\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/factorialhr.pt\/blog\/#website\",\"url\":\"https:\/\/factorialhr.pt\/blog\/\",\"name\":\"Factorial\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/factorialhr.pt\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/factorialhr.pt\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/factorialhr.pt\/blog\/#organization\",\"name\":\"All-in-one business management software - Factorial\",\"url\":\"https:\/\/factorialhr.pt\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\/\/factorialhr.pt\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/factorialhr.pt\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png\",\"contentUrl\":\"https:\/\/factorialhr.pt\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png\",\"width\":946,\"height\":880,\"caption\":\"All-in-one business management software - Factorial\"},\"image\":{\"@id\":\"https:\/\/factorialhr.pt\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/\",\"https:\/\/twitter.com\/factorialapp\",\"https:\/\/www.linkedin.com\/company\/factorialhr\",\"https:\/\/www.youtube.com\/@factorialmedia\",\"https:\/\/www.instagram.com\/factorial\/#\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"O sal\u00e1rio n\u00e3o basta para reter talento | Factorial","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/factorialhr.pt\/blog\/factorial-play\/videos\/o-salario-nao-basta-para-reter-talento\/","og_locale":"pt_PT","og_type":"article","og_title":"O sal\u00e1rio n\u00e3o basta para reter talento","og_url":"https:\/\/factorialhr.pt\/blog\/factorial-play\/videos\/o-salario-nao-basta-para-reter-talento\/","og_site_name":"Factorial","article_publisher":"https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/","og_image":[{"width":1200,"height":628,"url":"https:\/\/factorialhr.pt\/wp-content\/uploads\/2025\/11\/17131146\/factorial-open-graph.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@factorialapp","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/factorialhr.pt\/blog\/factorial-play\/videos\/o-salario-nao-basta-para-reter-talento\/","url":"https:\/\/factorialhr.pt\/blog\/factorial-play\/videos\/o-salario-nao-basta-para-reter-talento\/","name":"O sal\u00e1rio n\u00e3o basta para reter talento | Factorial","isPartOf":{"@id":"https:\/\/factorialhr.pt\/blog\/#website"},"datePublished":"2026-07-23T13:21:20+00:00","dateModified":"2026-07-23T13:21:20+00:00","inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/factorialhr.pt\/blog\/factorial-play\/videos\/o-salario-nao-basta-para-reter-talento\/"]}]},{"@type":"WebSite","@id":"https:\/\/factorialhr.pt\/blog\/#website","url":"https:\/\/factorialhr.pt\/blog\/","name":"Factorial","description":"","publisher":{"@id":"https:\/\/factorialhr.pt\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/factorialhr.pt\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-PT"},{"@type":"Organization","@id":"https:\/\/factorialhr.pt\/blog\/#organization","name":"All-in-one business management software - Factorial","url":"https:\/\/factorialhr.pt\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/factorialhr.pt\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/factorialhr.pt\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png","contentUrl":"https:\/\/factorialhr.pt\/wp-content\/uploads\/2023\/07\/18155144\/factorial-logo.png","width":946,"height":880,"caption":"All-in-one business management software - Factorial"},"image":{"@id":"https:\/\/factorialhr.pt\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/people\/Factorial\/100064908455810\/","https:\/\/twitter.com\/factorialapp","https:\/\/www.linkedin.com\/company\/factorialhr","https:\/\/www.youtube.com\/@factorialmedia","https:\/\/www.instagram.com\/factorial\/#"]}]}},"_links":{"self":[{"href":"https:\/\/factorialhr.pt\/blog\/wp-json\/wp\/v2\/factorial-videos\/196112"}],"collection":[{"href":"https:\/\/factorialhr.pt\/blog\/wp-json\/wp\/v2\/factorial-videos"}],"about":[{"href":"https:\/\/factorialhr.pt\/blog\/wp-json\/wp\/v2\/types\/factorial_video"}],"wp:attachment":[{"href":"https:\/\/factorialhr.pt\/blog\/wp-json\/wp\/v2\/media?parent=196112"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/factorialhr.pt\/blog\/wp-json\/wp\/v2\/categories?post=196112"},{"taxonomy":"factorial_category","embeddable":true,"href":"https:\/\/factorialhr.pt\/blog\/wp-json\/wp\/v2\/factorial-categories?post=196112"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}